{"id":303,"date":"2025-09-11T15:18:10","date_gmt":"2025-09-11T15:18:10","guid":{"rendered":"http:\/\/retroproject.eu\/?p=303"},"modified":"2025-09-11T15:18:10","modified_gmt":"2025-09-11T15:18:10","slug":"minor-zorgtechnologie","status":"publish","type":"post","link":"https:\/\/retroproject.eu\/en\/minor-zorgtechnologie\/","title":{"rendered":"Minor Zorgtechnologie"},"content":{"rendered":"<p>Techniek en gezondheidzorg raken steeds meer met elkaar verbonden. Het aanleren en gebruik van de diverse zorgtechnologie\u00ebn hebben vaak veel impact op de gebruikers, hulpverleners en organisaties. Het accent van de minor ligt op het vinden van de juiste balans tussen technologische (on)mogelijkheden en zorginhoudelijke overwegingen, zodat er een optimale afstemming wordt ontwikkeld tussen zorgtechniek en de gebruiker.<\/p>\n\n\n\n<p>In de minor Zorgtechnologie werken zorg- en technologiestudenten samen met cli\u00ebnten en professionals aan geselecteerde vraagstukken uit de gezondheidzorg. Deze vraagstukken kunnen worden beantwoord met inzet van (te ontwikkelen) digitale producten en diensten. Op de&nbsp;<a href=\"http:\/\/minorzorgtechnologie.wordpress.com\/introductie\/\" target=\"_blank\" rel=\"noreferrer noopener\">blog<\/a>&nbsp;van de minor is meer informatie en een overzicht van de afgeronde opdrachten te vinden.<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Techniek en gezondheidzorg raken steeds meer met elkaar verbonden. Het aanleren en gebruik van de diverse zorgtechnologie\u00ebn hebben vaak veel impact op de gebruikers, hulpverleners en organisaties. Het accent van de minor ligt op het vinden van de juiste balans tussen technologische (on)mogelijkheden en zorginhoudelijke overwegingen, zodat er een optimale afstemming wordt ontwikkeld tussen zorgtechniek en de gebruiker.<\/p>","protected":false},"author":1,"featured_media":304,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[36],"tags":[],"class_list":["post-303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-studenten"],"spectra_custom_meta":{"_edit_lock":["1757603898:1"],"_thumbnail_id":["304"],"_edit_last":["1"],"_uag_css_file_name":["uag-css-303.css"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:0;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}","a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:0;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uag_page_assets":["a:9:{s:3:\"css\";s:260:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:19:{i:0;s:10:\"core\/group\";i:1;s:12:\"core\/columns\";i:2;s:11:\"core\/column\";i:4;s:15:\"core\/navigation\";i:6;s:14:\"core\/site-logo\";i:9;s:21:\"trp\/language-switcher\";i:11;s:10:\"core\/image\";i:14;s:15:\"core\/post-title\";i:17;s:24:\"core\/post-featured-image\";i:20;s:14:\"core\/post-date\";i:21;s:17:\"core\/post-content\";i:22;s:11:\"core\/spacer\";i:24;s:12:\"core\/heading\";i:25;s:14:\"core\/paragraph\";i:26;s:11:\"core\/search\";i:27;s:17:\"core\/latest-posts\";i:28;s:20:\"core\/latest-comments\";i:29;s:13:\"core\/archives\";i:30;s:15:\"core\/categories\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1778649596\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/retroproject.eu\/wp-content\/uploads\/2025\/09\/img0313.jpg",320,240,false],"thumbnail":["https:\/\/retroproject.eu\/wp-content\/uploads\/2025\/09\/img0313-150x150.jpg",150,150,true],"medium":["https:\/\/retroproject.eu\/wp-content\/uploads\/2025\/09\/img0313-300x225.jpg",300,225,true],"medium_large":["https:\/\/retroproject.eu\/wp-content\/uploads\/2025\/09\/img0313.jpg",320,240,false],"large":["https:\/\/retroproject.eu\/wp-content\/uploads\/2025\/09\/img0313.jpg",320,240,false],"1536x1536":["https:\/\/retroproject.eu\/wp-content\/uploads\/2025\/09\/img0313.jpg",320,240,false],"2048x2048":["https:\/\/retroproject.eu\/wp-content\/uploads\/2025\/09\/img0313.jpg",320,240,false],"trp-custom-language-flag":["https:\/\/retroproject.eu\/wp-content\/uploads\/2025\/09\/img0313.jpg",16,12,false]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/retroproject.eu\/en\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Techniek en gezondheidzorg raken steeds meer met elkaar verbonden. Het aanleren en gebruik van de diverse zorgtechnologie\u00ebn hebben vaak veel impact op de gebruikers, hulpverleners en organisaties. Het accent van de minor ligt op het vinden van de juiste balans tussen technologische (on)mogelijkheden en zorginhoudelijke overwegingen, zodat er een optimale afstemming wordt ontwikkeld tussen zorgtechniek&hellip;","_links":{"self":[{"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/posts\/303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/comments?post=303"}],"version-history":[{"count":1,"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/posts\/303\/revisions"}],"predecessor-version":[{"id":305,"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/posts\/303\/revisions\/305"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/media\/304"}],"wp:attachment":[{"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/media?parent=303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/categories?post=303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/tags?post=303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}