{"id":2978,"date":"2026-04-09T17:03:14","date_gmt":"2026-04-09T15:03:14","guid":{"rendered":"https:\/\/retroproject.eu\/?p=2978"},"modified":"2026-04-09T17:04:28","modified_gmt":"2026-04-09T15:04:28","slug":"collaborative-intelligentie","status":"publish","type":"post","link":"https:\/\/retroproject.eu\/en\/collaborative-intelligentie\/","title":{"rendered":"Collaborative Intelligentie"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Arts-AI Samenwerkingen voor Oncologische Behandelplanning en Monitoring<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>Kunstmatige Intelligentie (AI) verandert de manier waarop we kankerscans bekijken. Onderzoek laat zien dat AI kanker sneller en vaak nauwkeuriger kan opsporen, tumoren kan afbakenen en behandelingsresultaten kan volgen, soms beter dan artsen. Toch wordt AI nog maar beperkt toegepast in ziekenhuizen, zowel in Nederland als wereldwijd. Dit is zorgelijk, want radiologen hebben te maken met hoge werkdruk, personeelstekorten en risico op burn-out.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Sommige taken in de oncologische beeldvorming, zoals het meten van tumoren of het aftekenen voor bestraling, zijn cruciaal maar ook repetitief en geestelijk vermoeiend. AI kan een groot deel van dit routinematige werk overnemen. Hierdoor houden artsen meer tijd en energie over voor wat echt telt: complexe beslissingen en samenwerking met andere specialisten om de beste zorg te plannen.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>De uitdaging is niet alleen slimme AI bouwen, maar ook zorgen dat deze technologie goed aansluit op ziekenhuisprocessen en het artsen daadwerkelijk ondersteunt in hun dagelijkse werkzaamheden.<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Arts-AI Samenwerkingen voor Oncologische Behandelplanning en Monitoring Kunstmatige Intelligentie (AI) verandert de manier waarop we kankerscans bekijken. Onderzoek laat zien dat AI kanker sneller en vaak nauwkeuriger kan opsporen, tumoren kan afbakenen en behandelingsresultaten kan volgen, soms beter dan artsen. Toch wordt AI nog maar beperkt toegepast in ziekenhuizen, zowel in Nederland als wereldwijd. Dit [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2979,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[25],"tags":[42,63,73],"class_list":["post-2978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-projects","tag-bin-yu","tag-gezondheid","tag-somaya-ben-allouch"],"spectra_custom_meta":{"_edit_lock":["1775747647:3"],"_thumbnail_id":["2979"],"_uag_css_file_name":["uag-css-2978.css"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:0;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uag_page_assets":["a:9:{s:3:\"css\";s:260:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:19:{i:0;s:10:\"core\/group\";i:1;s:12:\"core\/columns\";i:2;s:11:\"core\/column\";i:4;s:15:\"core\/navigation\";i:6;s:14:\"core\/site-logo\";i:9;s:21:\"trp\/language-switcher\";i:11;s:10:\"core\/image\";i:14;s:15:\"core\/post-title\";i:17;s:24:\"core\/post-featured-image\";i:20;s:14:\"core\/post-date\";i:21;s:17:\"core\/post-content\";i:22;s:11:\"core\/spacer\";i:24;s:12:\"core\/heading\";i:25;s:14:\"core\/paragraph\";i:26;s:11:\"core\/search\";i:27;s:17:\"core\/latest-posts\";i:28;s:20:\"core\/latest-comments\";i:29;s:13:\"core\/archives\";i:30;s:15:\"core\/categories\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1778645941\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/retroproject.eu\/wp-content\/uploads\/2026\/04\/Image_Arts-AI-Samenwerking-ZonMw2026-scaled.jpg",2560,1440,false],"thumbnail":["https:\/\/retroproject.eu\/wp-content\/uploads\/2026\/04\/Image_Arts-AI-Samenwerking-ZonMw2026-150x150.jpg",150,150,true],"medium":["https:\/\/retroproject.eu\/wp-content\/uploads\/2026\/04\/Image_Arts-AI-Samenwerking-ZonMw2026-300x169.jpg",300,169,true],"medium_large":["https:\/\/retroproject.eu\/wp-content\/uploads\/2026\/04\/Image_Arts-AI-Samenwerking-ZonMw2026-768x432.jpg",768,432,true],"large":["https:\/\/retroproject.eu\/wp-content\/uploads\/2026\/04\/Image_Arts-AI-Samenwerking-ZonMw2026-1024x576.jpg",1024,576,true],"1536x1536":["https:\/\/retroproject.eu\/wp-content\/uploads\/2026\/04\/Image_Arts-AI-Samenwerking-ZonMw2026-1536x864.jpg",1536,864,true],"2048x2048":["https:\/\/retroproject.eu\/wp-content\/uploads\/2026\/04\/Image_Arts-AI-Samenwerking-ZonMw2026-2048x1152.jpg",2048,1152,true],"trp-custom-language-flag":["https:\/\/retroproject.eu\/wp-content\/uploads\/2026\/04\/Image_Arts-AI-Samenwerking-ZonMw2026-18x10.jpg",18,10,true]},"uagb_author_info":{"display_name":"Leontine Born","author_link":"https:\/\/retroproject.eu\/en\/author\/leontine\/"},"uagb_comment_info":0,"uagb_excerpt":"Arts-AI Samenwerkingen voor Oncologische Behandelplanning en Monitoring Kunstmatige Intelligentie (AI) verandert de manier waarop we kankerscans bekijken. Onderzoek laat zien dat AI kanker sneller en vaak nauwkeuriger kan opsporen, tumoren kan afbakenen en behandelingsresultaten kan volgen, soms beter dan artsen. Toch wordt AI nog maar beperkt toegepast in ziekenhuizen, zowel in Nederland als wereldwijd. Dit&hellip;","_links":{"self":[{"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/posts\/2978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/comments?post=2978"}],"version-history":[{"count":2,"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/posts\/2978\/revisions"}],"predecessor-version":[{"id":2981,"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/posts\/2978\/revisions\/2981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/media\/2979"}],"wp:attachment":[{"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/media?parent=2978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/categories?post=2978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/tags?post=2978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}