{"id":2949,"date":"2026-03-11T15:21:59","date_gmt":"2026-03-11T14:21:59","guid":{"rendered":"https:\/\/retroproject.eu\/?p=2949"},"modified":"2026-03-19T15:20:01","modified_gmt":"2026-03-19T14:20:01","slug":"health-data-design-playground","status":"publish","type":"post","link":"https:\/\/retroproject.eu\/en\/health-data-design-playground\/","title":{"rendered":"Health-Data-Design-Playground"},"content":{"rendered":"<h3 class=\"wp-block-heading\">Innovating Data-Driven Everyday Health Interventions<\/h3>\n\n\n\n<p>&#8216;<strong>Wat als gezondheidsgegevens niet alleen in spreadsheets zouden staan, maar tot leven zouden komen via interactieve objecten en immersieve ruimtes om ons heen?&#8217;<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>De Health-Data-Design-Playground (HDDP) maakt deze visie werkelijkheid door ontwerpers in staat te stellen ruwe sensorgegevens om te zetten in boeiende, data-gestuurde dagelijkse gezondheidsinterventies door middel van praktische experimenten met gezondheidssensoren en persoonlijke gegevens.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Hoewel sensoren en technologie\u00ebn voor gezondheidsmonitoring steeds nauwkeurigere inzichten opleveren, slagen veel huidige gezondheidsinterventies er niet in om een lange termijn effect te bereiken vanwege een slechte integratie in het dagelijks leven en een gebrek aan boeiende interactie en ervaringsgericht ontwerp. HDDP overbrugt de kloof tussen ontwerp-intentie en technische implementatie.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Door toegankelijke sensorkits, gedeelde datasets en ontwerpgerichte softwarebronnen aan te bieden, verlaagt het platform de drempel om met complexe biosensoren en datapijplijnen te werken. Hierdoor kunnen ontwerpers verder gaan dan speculatieve concepten en snel prototypes maken voor de praktijk, wat de ontwikkeling van haalbare, ervaringsgerichte en mensgerichte gezondheidsoplossingen ondersteunt.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Als gedeelde onderwijs- en innovatie-infrastructuur binnen de HvA ondersteunt HDDP interdisciplinair onderwijs en samenwerking tussen opleidingen op het gebied van ontwerp, gezondheid en technologie. Op de lange termijn streeft HDDP naar het bevorderen van zinvolle, boeiende en duurzame gezondheidsinterventies die persoonlijke reflectie stimuleren, gedragsverandering ondersteunen en participatieve gezondheidszorg versterken naast traditionele klinische zorg.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Image &amp; Video<\/h4>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"padding-top:var(--wp--preset--spacing--20)\">Publications<\/h4>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"padding-top:var(--wp--preset--spacing--20)\">Project duration<\/h4>\n\n\n\n<p>1 maart 2026 &#8211; 1 februari 2027<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"padding-top:var(--wp--preset--spacing--20);padding-bottom:0\">Project manager<\/h4>\n\n\n\n<p><a href=\"https:\/\/retroproject.eu\/en\/dr-bin-yu\/\" data-type=\"post\" data-id=\"1124\">Bin Yu<\/a><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"padding-top:var(--wp--preset--spacing--30)\">Researchers<\/h4>\n\n\n\n<p>nvt<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"padding-top:var(--wp--preset--spacing--20);padding-bottom:0\">Funding<\/h4>\n\n\n\n<p>Centre of Expertise Creative Innovation<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"padding-top:var(--wp--preset--spacing--20)\">Partners<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.a-plus-n.com\/\" data-type=\"link\" data-id=\"https:\/\/www.a-plus-n.com\/\">A+N Studio<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.rogierarents.nl\/\" data-type=\"link\" data-id=\"https:\/\/www.rogierarents.nl\/\">Studio Rogier Arents<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/fashiontechfarm.com\/\" data-type=\"link\" data-id=\"https:\/\/fashiontechfarm.com\/\">Fashion Tech Farm<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.tue.nl\/en\/our-university\/departments\/industrial-design\" data-type=\"link\" data-id=\"https:\/\/www.tue.nl\/en\/our-university\/departments\/industrial-design\">TU\/e Industrial Design<\/a><\/li>\n<\/ul>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Innovating Data-Driven Everyday Health Interventions &#8216;Wat als gezondheidsgegevens niet alleen in spreadsheets zouden staan, maar tot leven zouden komen via interactieve objecten en immersieve ruimtes om ons heen?&#8217; De Health-Data-Design-Playground (HDDP) maakt deze visie werkelijkheid door ontwerpers in staat te stellen ruwe sensorgegevens om te zetten in boeiende, data-gestuurde dagelijkse gezondheidsinterventies door middel van praktische [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2964,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[25],"tags":[63],"class_list":["post-2949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-projects","tag-gezondheid"],"spectra_custom_meta":{"_edit_lock":["1773930075:3"],"_thumbnail_id":["2964"],"_uag_css_file_name":["uag-css-2949.css"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:0;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uag_page_assets":["a:9:{s:3:\"css\";s:260:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:21:{i:0;s:10:\"core\/group\";i:1;s:12:\"core\/columns\";i:2;s:11:\"core\/column\";i:4;s:15:\"core\/navigation\";i:6;s:14:\"core\/site-logo\";i:9;s:21:\"trp\/language-switcher\";i:11;s:10:\"core\/image\";i:14;s:15:\"core\/post-title\";i:17;s:24:\"core\/post-featured-image\";i:20;s:14:\"core\/post-date\";i:21;s:17:\"core\/post-content\";i:22;s:11:\"core\/spacer\";i:24;s:12:\"core\/heading\";i:25;s:14:\"core\/paragraph\";i:26;s:9:\"core\/list\";i:27;s:14:\"core\/list-item\";i:28;s:11:\"core\/search\";i:29;s:17:\"core\/latest-posts\";i:30;s:20:\"core\/latest-comments\";i:31;s:13:\"core\/archives\";i:32;s:15:\"core\/categories\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1778645684\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/retroproject.eu\/wp-content\/uploads\/2026\/03\/Beeld-Nieuws-HDDP-CoECI-2026.png",235,204,false],"thumbnail":["https:\/\/retroproject.eu\/wp-content\/uploads\/2026\/03\/Beeld-Nieuws-HDDP-CoECI-2026-150x150.png",150,150,true],"medium":["https:\/\/retroproject.eu\/wp-content\/uploads\/2026\/03\/Beeld-Nieuws-HDDP-CoECI-2026.png",235,204,false],"medium_large":["https:\/\/retroproject.eu\/wp-content\/uploads\/2026\/03\/Beeld-Nieuws-HDDP-CoECI-2026.png",235,204,false],"large":["https:\/\/retroproject.eu\/wp-content\/uploads\/2026\/03\/Beeld-Nieuws-HDDP-CoECI-2026.png",235,204,false],"1536x1536":["https:\/\/retroproject.eu\/wp-content\/uploads\/2026\/03\/Beeld-Nieuws-HDDP-CoECI-2026.png",235,204,false],"2048x2048":["https:\/\/retroproject.eu\/wp-content\/uploads\/2026\/03\/Beeld-Nieuws-HDDP-CoECI-2026.png",235,204,false],"trp-custom-language-flag":["https:\/\/retroproject.eu\/wp-content\/uploads\/2026\/03\/Beeld-Nieuws-HDDP-CoECI-2026-14x12.png",14,12,true]},"uagb_author_info":{"display_name":"Leontine Born","author_link":"https:\/\/retroproject.eu\/en\/author\/leontine\/"},"uagb_comment_info":0,"uagb_excerpt":"Innovating Data-Driven Everyday Health Interventions &#8216;Wat als gezondheidsgegevens niet alleen in spreadsheets zouden staan, maar tot leven zouden komen via interactieve objecten en immersieve ruimtes om ons heen?&#8217; De Health-Data-Design-Playground (HDDP) maakt deze visie werkelijkheid door ontwerpers in staat te stellen ruwe sensorgegevens om te zetten in boeiende, data-gestuurde dagelijkse gezondheidsinterventies door middel van praktische&hellip;","_links":{"self":[{"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/posts\/2949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/comments?post=2949"}],"version-history":[{"count":2,"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/posts\/2949\/revisions"}],"predecessor-version":[{"id":2954,"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/posts\/2949\/revisions\/2954"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/media\/2964"}],"wp:attachment":[{"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/media?parent=2949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/categories?post=2949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/retroproject.eu\/en\/wp-json\/wp\/v2\/tags?post=2949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}